{"id":8815,"date":"2025-08-31T14:58:19","date_gmt":"2025-08-31T14:58:19","guid":{"rendered":"https:\/\/stolpersteine-goeppingen.de\/?page_id=8815"},"modified":"2025-08-31T15:40:30","modified_gmt":"2025-08-31T15:40:30","slug":"juedische-schule","status":"publish","type":"page","link":"https:\/\/stolpersteine-goeppingen.de\/en\/goeppingen\/juedische-schule\/","title":{"rendered":"Jewish School in G\u00f6ppingen"},"content":{"rendered":"\n<p>see <a href=\"https:\/\/stolpersteine-goeppingen.de\/en\/goeppingen\/erlanger-fritz-max\/\" data-type=\"page\" data-id=\"376\">Erlanger, Fritz Max (and the Jewish School in G\u00f6ppingen)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>see Erlanger, Fritz Max (and the Jewish School in G\u00f6ppingen)<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":118,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","ngg_post_thumbnail":0,"cybocfi_hide_featured_image":"","footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-8815","page","type-page","status-publish","hentry","post-preview"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:18:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/pages\/8815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/comments?post=8815"}],"version-history":[{"count":7,"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/pages\/8815\/revisions"}],"predecessor-version":[{"id":8872,"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/pages\/8815\/revisions\/8872"}],"up":[{"embeddable":true,"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/pages\/118"}],"wp:attachment":[{"href":"https:\/\/stolpersteine-goeppingen.de\/en\/wp-json\/wp\/v2\/media?parent=8815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}